{"id":11922,"date":"2016-06-02T16:04:27","date_gmt":"2016-06-02T19:04:27","guid":{"rendered":"http:\/\/jornalcontato.com.br\/home\/?p=11922"},"modified":"2016-06-02T16:24:39","modified_gmt":"2016-06-02T19:24:39","slug":"taubate-protestos-contra-o-estupro-nathalia-de-oliveira","status":"publish","type":"post","link":"https:\/\/www.jornalcontato.com.br\/home\/index.php\/taubate-protestos-contra-o-estupro-nathalia-de-oliveira\/","title":{"rendered":"Taubat\u00e9: protestos contra o estupro (Nath\u00e1lia de Oliveira)"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><\/strong><strong><em>Coletivos feministas realizam manifesta\u00e7\u00f5es; a maioria dos crimes \u00e9 de autoria familiar; na terra de Lobato, grupo vinculado \u00e0 Unitau presta atendimento gratuito \u00e0s v\u00edtimas de viol\u00eancia sexual<!--more--><\/em><\/strong><\/p>\n<p style=\"text-align: center;\">\u201c<em>Est\u00e1 de noite. Voc\u00ea acabou de sair do trabalho e est\u00e1 voltando pra casa a p\u00e9 e sozinha. Voc\u00ea precisava terminar uma planilha que o chefe usaria na reuni\u00e3o na manh\u00e3 do outro dia e, por isso, ficou al\u00e9m do hor\u00e1rio no escrit\u00f3rio. Por ser muito mais tarde do que o habitual, as casas j\u00e1 est\u00e3o trancadas e a maioria com as luzes apagadas. N\u00e3o tem ningu\u00e9m na rua, exceto um grupo de homens conversando e rindo na frente de um port\u00e3o de uma resid\u00eancia. Um deles est\u00e1 dentro de um carro com as portas abertas. Voc\u00ea aumenta a velocidade dos passos e troca de cal\u00e7ada para colocar mais dist\u00e2ncia do grupo. Voc\u00ea mant\u00e9m o olhar pra frente para evitar chamar aten\u00e7\u00e3o. A cada passo parece que as risadas est\u00e3o mais pr\u00f3ximas e o grito j\u00e1 est\u00e1 preso na garganta at\u00e9 que voc\u00ea chega ao fim da rua e fica aliviada que nada aconteceu\u201d<\/em>.<\/p>\n<p>O caso relatado acima \u00e9 fict\u00edcio, mas n\u00e3o est\u00e1 distante da realidade. Ele retrata o medo que muitas mulheres t\u00eam diariamente. De acordo com uma pesquisa divulgada no dia 20 de maio pela Organiza\u00e7\u00e3o Internacional de Combate a Pobreza ActionAid, 50% das 503 mulheres brasileiras entrevistadas, j\u00e1 foram seguidas nas ruas e 86% delas j\u00e1 sofreram alguma forma de ass\u00e9dio em locais p\u00fablicos.<\/p>\n<p><a href=\"http:\/\/jornalcontato.com.br\/home\/wp-content\/uploads\/2016\/06\/01-Protesto-reduzida.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-11924\" title=\"01 Protesto reduzida\" src=\"http:\/\/jornalcontato.com.br\/home\/wp-content\/uploads\/2016\/06\/01-Protesto-reduzida-450x312.jpg\" alt=\"\" width=\"450\" height=\"312\" srcset=\"https:\/\/jornalcontato.com.br\/home\/wp-content\/uploads\/2016\/06\/01-Protesto-reduzida-450x312.jpg 450w, https:\/\/jornalcontato.com.br\/home\/wp-content\/uploads\/2016\/06\/01-Protesto-reduzida-300x208.jpg 300w, https:\/\/jornalcontato.com.br\/home\/wp-content\/uploads\/2016\/06\/01-Protesto-reduzida.jpg 668w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><em><strong>\u00c9 preciso muita coragem para enfrentar a cultura machista dominante<\/strong><\/em><\/p>\n<p><strong>Dia de luta<\/strong><\/p>\n<p>Na quarta-feira, 01 de junho, diversas cidades do Brasil promoveram atos contra a cultura do estupro, inclusive em Taubat\u00e9, onde cerca de 130 pessoas participaram da Marcha das Flores. O protesto foi organizado pelos coletivos feministas <strong><em>Maria, vem com as outras<\/em><\/strong> e <strong><em>Maria Lacerda de Moura<\/em><\/strong>.<\/p>\n<p>Por volta das 17h:30, apesar da chuva que amea\u00e7ava cair a qualquer momento, os manifestantes se encontraram na Pra\u00e7a Dom Epaminondas, da Catedral, onde cantaram m\u00fasicas de empoderamento feminino e contra ao estupro. Algumas das jovens levavam cartazes, velas e flores. \u201cN\u00f3s falamos quais s\u00e3o as nossas frustra\u00e7\u00f5es, as nossas reivindica\u00e7\u00f5es e tentamos passar isso para frente; levantar esses questionamentos para quem est\u00e1 passando aqui por perto para que pense e leve isso pra casa\u201d, explica Gabriella Fieschi, uma das organizadoras do ato, membro do Coletivo Feminista Maria Lacerda de Moura.<\/p>\n<p>Na Pra\u00e7a, foram realizadas apresenta\u00e7\u00f5es condenando a culpabiliza\u00e7\u00e3o da v\u00edtima em casos de ass\u00e9dio sexual e acesas as velas como representa\u00e7\u00e3o e resist\u00eancia ao machismo predominante na sociedade. Em seguida, as manifestantes caminharam pelas principais ruas do Centro at\u00e9 chegarem \u00e0 Rua Nove de Julho, onde continuaram o protesto.<\/p>\n<p>Manifesta\u00e7\u00f5es como essa que foram realizadas em diversas outras cidades do pa\u00eds tiveram origem no Rio de Janeiro na semana passada depois que uma adolescente de 16 anos foi estuprada por cerca de 30 homens. \u201cN\u00f3s todas nos comovemos com o que aconteceu no Rio e, por isso, nos mobilizamos com os coletivos da cidade para fazermos esse ato\u201d, afirma Gabriella.<\/p>\n<p><a href=\"http:\/\/jornalcontato.com.br\/home\/wp-content\/uploads\/2016\/06\/03-Protesto-reduzida.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-11925\" title=\"03 Protesto reduzida\" src=\"http:\/\/jornalcontato.com.br\/home\/wp-content\/uploads\/2016\/06\/03-Protesto-reduzida-450x270.jpg\" alt=\"\" width=\"450\" height=\"270\" srcset=\"https:\/\/jornalcontato.com.br\/home\/wp-content\/uploads\/2016\/06\/03-Protesto-reduzida-450x270.jpg 450w, https:\/\/jornalcontato.com.br\/home\/wp-content\/uploads\/2016\/06\/03-Protesto-reduzida-300x180.jpg 300w, https:\/\/jornalcontato.com.br\/home\/wp-content\/uploads\/2016\/06\/03-Protesto-reduzida.jpg 693w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><em><strong>Mesmo com a noite chuvosa e senhoras idosas que reclamavam das manifestantes, as feministas n\u00e3o arredaram o p\u00e9 e caminharam depois at\u00e9 a pra\u00e7a Santa Terezinha\u00a0<\/strong><\/em><\/p>\n<p><strong>Estat\u00edsticas pesadas<\/strong><\/p>\n<p>Segundo dados da Secretaria de Seguran\u00e7a P\u00fablica do Estado de S\u00e3o Paulo (SSP), entre Janeiro e Abril deste ano j\u00e1 foram contabilizados 16 casos de estupro em Taubat\u00e9. Em todo o Vale do Para\u00edba j\u00e1 foram registradas 209 ocorr\u00eancias. Na ter\u00e7a-feira, 31, uma advogada de S\u00e3o Jos\u00e9 dos Campos foi violentada por um homem. A mulher sa\u00eda do trabalho para almo\u00e7ar quando foi abordada pelo criminoso que a for\u00e7ou a dirigir at\u00e9 um local afastado na cidade, onde cometeu o crime. A advogada registrou o BO na Delegacia da Mulher, mas o homem ainda n\u00e3o foi encontrado.<\/p>\n<p>Apesar da estat\u00edstica da SSP, o n\u00famero n\u00e3o representa a quantidade real de casos devido ao medo da v\u00edtima em registrar a viol\u00eancia. \u201cA pessoa adulta [tem medo] porque normalmente \u00e9 amea\u00e7ada de morte. Ela n\u00e3o se sente segura em ir at\u00e9 a delegacia e registrar a ocorr\u00eancia\u201d, explica o advogado Avelino Alves J\u00fanior. \u201cJ\u00e1 [em rela\u00e7\u00e3o] \u00e0s crian\u00e7as, o motivo \u00e9 porque elas s\u00e3o desacreditadas pelos pr\u00f3prios pais que preferem acreditar no padrasto, no tio ou em quem quer que tenha cometido o crime\u201d.<\/p>\n<p>Para a feminista Gabriella Fieschi, a abordagem nas delegacias tamb\u00e9m \u00e9 um fato que amedronta as v\u00edtimas. \u201cAs delegacias est\u00e3o muito sucateadas e muitas vezes s\u00e3o homens que fazem o atendimento. N\u00e3o d\u00e1 para julgar a v\u00edtima por n\u00e3o se sentir a vontade em falar com um homem sobre isso\u201d, destaca. \u201cConhe\u00e7o hist\u00f3rias de v\u00edtimas que foram at\u00e9 a delegacia e o delegado ficava questionando qual roupa ela usava e se ela estava b\u00eabada. Totalmente constrangedor. E ela tem que reviver mil vezes a dor do estupro quando vai fazer o BO\u201d, ressalta Gabriella.<\/p>\n<p><a href=\"http:\/\/jornalcontato.com.br\/home\/wp-content\/uploads\/2016\/06\/04-Protesto-reduzida.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-11930\" title=\"04 Protesto reduzida\" src=\"http:\/\/jornalcontato.com.br\/home\/wp-content\/uploads\/2016\/06\/04-Protesto-reduzida-450x281.jpg\" alt=\"\" width=\"450\" height=\"281\" srcset=\"https:\/\/jornalcontato.com.br\/home\/wp-content\/uploads\/2016\/06\/04-Protesto-reduzida-450x281.jpg 450w, https:\/\/jornalcontato.com.br\/home\/wp-content\/uploads\/2016\/06\/04-Protesto-reduzida-300x187.jpg 300w, https:\/\/jornalcontato.com.br\/home\/wp-content\/uploads\/2016\/06\/04-Protesto-reduzida.jpg 698w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><em><strong>Discursos, cantos e palavras de ordem contra o machismo marcaram a manifesta\u00e7\u00e3o<\/strong><\/em><\/p>\n<p><strong>Apoio<\/strong><\/p>\n<p>Avelino Alves J\u00fanior \u00e9 consultor jur\u00eddico do Gavvis, Grupo de Atendimento \u00e0 V\u00edtima de Viol\u00eancia Sexual, vinculado \u00e0 Pr\u00f3-reitoria de Extens\u00e3o e Rela\u00e7\u00f5es Comunit\u00e1rias da Universidade de Taubat\u00e9. O grupo conta com profissionais de Medicina, de Enfermagem, de Psicologia e de Direito e atende pacientes encaminhados pelo Pronto Socorro, delegacias ou que chegam diretamente ao Gavvis.<\/p>\n<p>As consultas s\u00e3o realizadas no Hospital Universit\u00e1rio todas as segundas-feiras e s\u00e3o realizados exames laboratoriais para identifica\u00e7\u00e3o de doen\u00e7as sexualmente transmiss\u00edveis, tratamento psicol\u00f3gico pr\u00e9 e p\u00f3s-traum\u00e1tico e aconselhamento jur\u00eddico. Todas as a\u00e7\u00f5es realizadas pelo Gavvis s\u00e3o gratuitas.<\/p>\n<p><strong>De acordo com o advogado, o Gavvis atualmente atende cinco pacientes por semana, das quais tr\u00eas s\u00e3o crian\u00e7as. \u201cA maioria dos casos que chegam at\u00e9 a gente s\u00e3o crian\u00e7as com menos de 12 anos de idade\u201d, destaca Avelino. A maioria dos casos de viol\u00eancia sexual que chegam at\u00e9 o grupo \u00e9 de casos que aconteceram dentro da casa da v\u00edtima. O crime normalmente \u00e9 praticado pelo pai, padrasto ou marido. \u201cNa maioria dos casos, o crime foi cometido pelos pr\u00f3prios familiares da v\u00edtima\u201d, conclui o consultor jur\u00eddico.\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Coletivos feministas realizam manifesta\u00e7\u00f5es; a maioria dos crimes \u00e9 de autoria familiar; na terra de Lobato, grupo vinculado \u00e0 Unitau presta atendimento gratuito \u00e0s v\u00edtimas &#8230;<\/p>\n","protected":false},"author":1,"featured_media":11923,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,29,7],"tags":[],"class_list":["post-11922","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","category-regional","category-reportagem"],"_links":{"self":[{"href":"https:\/\/www.jornalcontato.com.br\/home\/index.php\/wp-json\/wp\/v2\/posts\/11922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jornalcontato.com.br\/home\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jornalcontato.com.br\/home\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jornalcontato.com.br\/home\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jornalcontato.com.br\/home\/index.php\/wp-json\/wp\/v2\/comments?post=11922"}],"version-history":[{"count":5,"href":"https:\/\/www.jornalcontato.com.br\/home\/index.php\/wp-json\/wp\/v2\/posts\/11922\/revisions"}],"predecessor-version":[{"id":11928,"href":"https:\/\/www.jornalcontato.com.br\/home\/index.php\/wp-json\/wp\/v2\/posts\/11922\/revisions\/11928"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jornalcontato.com.br\/home\/index.php\/wp-json\/wp\/v2\/media\/11923"}],"wp:attachment":[{"href":"https:\/\/www.jornalcontato.com.br\/home\/index.php\/wp-json\/wp\/v2\/media?parent=11922"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jornalcontato.com.br\/home\/index.php\/wp-json\/wp\/v2\/categories?post=11922"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jornalcontato.com.br\/home\/index.php\/wp-json\/wp\/v2\/tags?post=11922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}